{"id":1,"count":8734,"description":"","link":"https:\/\/cryptonews.com\/it\/news\/","name":"News","slug":"news","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ultime notizie sulle crypto | Resta sempre aggiornato | Cryptonews Italia<\/title>\n<meta name=\"description\" content=\"Leggi le ultime notizie sulle criptovalute e blockchain per rimanere sempre aggiornato: news, eventi recenti e movimenti dei prezzi. Solo su Cryptonews Italia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/it\/news\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ultime notizie sulle crypto | Resta sempre aggiornato | Cryptonews Italia\" \/>\n<meta property=\"og:description\" content=\"Leggi le ultime notizie sulle criptovalute e blockchain per rimanere sempre aggiornato: news, eventi recenti e movimenti dei prezzi. Solo su Cryptonews Italia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/it\/news\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Italia\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/09\/4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1669\" \/>\n\t<meta property=\"og:image:height\" content=\"874\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/p\/assets\/empty-cryptonews.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ultime notizie sulle crypto | Resta sempre aggiornato | Cryptonews Italia","description":"Leggi le ultime notizie sulle criptovalute e blockchain per rimanere sempre aggiornato: news, eventi recenti e movimenti dei prezzi. Solo su Cryptonews Italia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/it\/news\/","og_locale":"it_IT","og_type":"article","og_title":"Ultime notizie sulle crypto | Resta sempre aggiornato | Cryptonews Italia","og_description":"Leggi le ultime notizie sulle criptovalute e blockchain per rimanere sempre aggiornato: news, eventi recenti e movimenti dei prezzi. Solo su Cryptonews Italia","og_url":"https:\/\/cryptonews.com\/it\/news\/","og_site_name":"Cryptonews Italia","og_image":[{"width":1669,"height":874,"url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/09\/4.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/p\/assets\/empty-cryptonews.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/cryptonews.com\/it\/news\/","url":"https:\/\/cryptonews.com\/it\/news\/","name":"Ultime notizie sulle crypto | Resta sempre aggiornato | Cryptonews Italia","isPartOf":{"@id":"https:\/\/cryptonews.com\/it\/#website"},"description":"Leggi le ultime notizie sulle criptovalute e blockchain per rimanere sempre aggiornato: news, eventi recenti e movimenti dei prezzi. Solo su Cryptonews Italia","breadcrumb":{"@id":"https:\/\/cryptonews.com\/it\/news\/#breadcrumb"},"inLanguage":"it-IT","author":[]},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/it\/news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/it\/"},{"@type":"ListItem","position":2,"name":"News"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/it\/#website","url":"https:\/\/cryptonews.com\/it\/","name":"Cryptonews Italia","description":"Le notizie pi\u00f9 importanti sulle valute digitali","publisher":{"@id":"https:\/\/cryptonews.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/it\/#organization","name":"Cryptonews Italia","url":"https:\/\/cryptonews.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/8\/2023\/10\/cropped-favicon_big.png","width":512,"height":512,"caption":"Cryptonews Italia"},"image":{"@id":"https:\/\/cryptonews.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/posts?categories=1"},{"href":"https:\/\/cryptonews.com\/it\/wp-json\/wp\/v2\/coins?categories=1"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}