{"id":811,"count":91,"description":"","link":"https:\/\/bitcoinmagazine.com\/tags\/tether","name":"Tether","slug":"tether","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/bitcoinmagazine.com\/wp-json\/wp\/v2\/tags\/811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinmagazine.com\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bitcoinmagazine.com\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bitcoinmagazine.com\/wp-json\/wp\/v2\/posts?tags=811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}