{"id":1991,"count":14,"description":"","link":"https:\/\/bitcoinmagazine.com\/tags\/executive-order","name":"Executive Order","slug":"executive-order","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/bitcoinmagazine.com\/wp-json\/wp\/v2\/tags\/1991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bitcoinmagazine.com\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/bitcoinmagazine.com\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/bitcoinmagazine.com\/wp-json\/wp\/v2\/posts?tags=1991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}